{"id":25,"date":"2022-09-07T13:52:36","date_gmt":"2022-09-07T13:52:36","guid":{"rendered":"http:\/\/dummy.xtemos.com\/woodmart2\/accessories-elementor\/?page_id=25"},"modified":"2025-10-20T05:13:11","modified_gmt":"2025-10-20T05:13:11","slug":"home","status":"publish","type":"page","link":"https:\/\/chstar.xyz\/pt\/","title":{"rendered":"Home"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"25\" class=\"elementor elementor-25\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-1a3e86c e-flex e-con-boxed e-con e-parent\" data-id=\"1a3e86c\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-491dec4 elementor-widget elementor-widget-wd_products_tabs\" data-id=\"491dec4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-tabs wd-products-tabs tabs-design-simple\">\n\t\t\t<div class=\"wd-tabs-header text-center\">\n\t\t\t\t\t\t\t\t\t<div class=\"tabs-name title\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"tabs-text\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\tNew Products\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-nav-wrapper wd-nav-tabs-wrapper tabs-navigation-wrapper\">\n\n\t\t\t\t\t<ul class=\"wd-nav wd-nav-tabs products-tabs-title wd-style-default wd-icon-pos-left\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li data-atts=\"{&quot;layout&quot;:&quot;grid&quot;,&quot;pagination&quot;:&quot;&quot;,&quot;pagination_arrows_position&quot;:&quot;together&quot;,&quot;items_per_page&quot;:12,&quot;spacing&quot;:&quot;20&quot;,&quot;spacing_tablet&quot;:&quot;&quot;,&quot;spacing_mobile&quot;:&quot;&quot;,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;product_hover&quot;:&quot;inherit&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product_tablet&quot;:0,&quot;stretch_product_mobile&quot;:0,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:0,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_bordered_grid_style&quot;:null,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;products_color_scheme&quot;:&quot;default&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;elementor&quot;:true,&quot;sync_parent_id&quot;:null,&quot;slides_per_view&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;wrap&quot;:null,&quot;autoheight&quot;:null,&quot;autoplay&quot;:null,&quot;speed&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;carousel_sync&quot;:null,&quot;sync_child_id&quot;:null,&quot;img_size_custom&quot;:null,&quot;stretch_product&quot;:null,&quot;grid_gallery&quot;:&quot;&quot;,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;lazy_loading&quot;:&quot;no&quot;,&quot;post_type&quot;:&quot;product&quot;,&quot;ajax_recently_viewed&quot;:null,&quot;include&quot;:null,&quot;taxonomies&quot;:&quot;&quot;,&quot;orderby&quot;:&quot;&quot;,&quot;offset&quot;:&quot;&quot;,&quot;query_type&quot;:&quot;OR&quot;,&quot;order&quot;:&quot;&quot;,&quot;hide_out_of_stock&quot;:&quot;no&quot;,&quot;meta_key&quot;:null,&quot;exclude&quot;:&quot;&quot;}\" class=\"wd-active\">\n\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-nav-link\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tab-label nav-link-text\">\n\t\t\t\t\t\t\t\t\t\tNew product 1\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-tabs-content-wrapper\">\n\t\t\t\t\t<div class=\"wd-sticky-loader\"><span class=\"wd-loader\"><\/span><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wd-products-element wd-tab-content wd-active wd-in\">\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"products wd-products grid-columns-4 elements-grid wd-grid-g\" data-paged=\"1\" data-atts=\"{&quot;speed&quot;:null,&quot;slides_per_view&quot;:null,&quot;wrap&quot;:null,&quot;autoplay&quot;:null,&quot;autoheight&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;carousel_sync&quot;:null,&quot;sync_parent_id&quot;:null,&quot;sync_child_id&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;include&quot;:null,&quot;meta_key&quot;:null,&quot;ajax_recently_viewed&quot;:null,&quot;pagination_arrows_position&quot;:&quot;together&quot;,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:4,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product&quot;:null,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_bordered_grid_style&quot;:null,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;img_size_custom&quot;:null,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;force_not_ajax&quot;:&quot;no&quot;,&quot;wrapper_classes&quot;:&quot; wd-tab-content wd-active wd-in&quot;,&quot;elementor&quot;:true}\" data-source=\"shortcode\" data-columns=\"4\" data-grid-gallery=\"\" style=\"--wd-col-lg:4;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product tm-has-options type-product post-12613 status-publish instock product_cat-mens has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"12613\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1801-style-nylon-cool-pique-b385\/\" class=\"product-image-link\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12613\" data-id=\"12613\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1801-style-nylon-cool-pique-b385\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12613\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12613\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12613\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12613\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12613\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1801 style, nylon cool pique (B385)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1801 style, nylon cool pique (B385)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1801 style, nylon cool pique (B385)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12613\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1801-style-nylon-cool-pique-b385\/\">1801 style, nylon cool pique (B385)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/mens\/\" rel=\"tag\">Men\u2019s<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12618 status-publish instock product_cat-mens has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"2\" data-id=\"12618\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1801-style-nylon-cool-pique-b386\/\" class=\"product-image-link\">\n\t\t\t<img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12618\" data-id=\"12618\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1801-style-nylon-cool-pique-b386\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12618\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12618\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12618\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12618\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12618\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1801 style, nylon cool pique (B386)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1801 style, nylon cool pique (B386)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1801 style, nylon cool pique (B386)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12618\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1801-style-nylon-cool-pique-b386\/\">1801 style, nylon cool pique (B386)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/mens\/\" rel=\"tag\">Men\u2019s<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12623 status-publish last instock product_cat-mens has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"3\" data-id=\"12623\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1802-style-nylon-cool-pique-b388\/\" class=\"product-image-link\">\n\t\t\t<img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12623\" data-id=\"12623\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1802-style-nylon-cool-pique-b388\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12623\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12623\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12623\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12623\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12623\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1802 style, nylon cool pique (B388)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1802 style, nylon cool pique (B388)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1802 style, nylon cool pique (B388)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12623\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1802-style-nylon-cool-pique-b388\/\">1802 style, nylon cool pique (B388)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/mens\/\" rel=\"tag\">Men\u2019s<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12628 status-publish first instock product_cat-mens has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"4\" data-id=\"12628\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1802-style-nylon-cool-pique-b389\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12628\" data-id=\"12628\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1802-style-nylon-cool-pique-b389\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12628\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12628\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12628\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12628\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12628\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1802 style, nylon cool pique (B389)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1802 style, nylon cool pique (B389)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1802 style, nylon cool pique (B389)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12628\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1802-style-nylon-cool-pique-b389\/\">1802 style, nylon cool pique (B389)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/mens\/\" rel=\"tag\">Men\u2019s<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12633 status-publish instock product_cat-new-models has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"12633\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b0d\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12633\" data-id=\"12633\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b0d\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12633\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12633\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12633\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12633\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12633\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1805 Style, Nylon Cool (4B0D)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1805 Style, Nylon Cool (4B0D)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1805 Style, Nylon Cool (4B0D)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12633\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b0d\/\">1805 Style, Nylon Cool (4B0D)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/new-models\/\" rel=\"tag\">New models<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12638 status-publish instock product_cat-new-models has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"6\" data-id=\"12638\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b1d\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12638\" data-id=\"12638\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b1d\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12638\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12638\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12638\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12638\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12638\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1805 Style, Nylon Cool (4B1D)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1805 Style, Nylon Cool (4B1D)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1805 Style, Nylon Cool (4B1D)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12638\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b1d\/\">1805 Style, Nylon Cool (4B1D)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/new-models\/\" rel=\"tag\">New models<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12643 status-publish last instock product_cat-new-models has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"12643\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b2d\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12643\" data-id=\"12643\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b2d\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12643\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12643\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12643\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12643\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12643\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1805 Style, Nylon Cool (4B2D)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1805 Style, Nylon Cool (4B2D)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1805 Style, Nylon Cool (4B2D)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12643\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b2d\/\">1805 Style, Nylon Cool (4B2D)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/new-models\/\" rel=\"tag\">New models<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12663 status-publish first instock product_cat-short-sleeve-suit has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"12663\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/a081-hooded-four-seasons-fitness-pants\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-853x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-853x1024.jpg 853w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-250x300.jpg 250w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-768x922.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-1280x1536.jpg 1280w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-10x12.jpg 10w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-1200x1440.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-148x178.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58.jpg 1600w\" sizes=\"(max-width: 853px) 100vw, 853px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12663\" data-id=\"12663\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/a081-hooded-four-seasons-fitness-pants\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12663\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12663\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12663\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12663\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12663\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;A081 hooded four seasons fitness pants&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;A081 hooded four seasons fitness pants&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"A081 hooded four seasons fitness pants\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12663\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/a081-hooded-four-seasons-fitness-pants\/\">A081 hooded four seasons fitness pants<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/short-sleeve-suit\/\" rel=\"tag\">Short sleeve suit<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12596 status-publish instock product_cat-women has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"12596\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/a208-dress-s-xxl\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-819x1024.jpg 819w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-240x300.jpg 240w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-768x960.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-1229x1536.jpg 1229w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-10x12.jpg 10w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-1200x1500.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-148x185.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8.jpg 1600w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12596\" data-id=\"12596\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/a208-dress-s-xxl\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12596\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12596\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12596\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12596\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12596\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;A208# Dress S----XXL&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;A208# Dress S----XXL&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"A208# Dress S----XXL\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12596\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/a208-dress-s-xxl\/\">A208# Dress S&#8212;-XXL<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/women\/\" rel=\"tag\">Women<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12604 status-publish instock product_cat-women has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"12604\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/a209-dress-s-xxl\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-819x1024.jpg 819w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-240x300.jpg 240w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-768x960.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-1229x1536.jpg 1229w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-10x12.jpg 10w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-1200x1500.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-148x185.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6.jpg 1600w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12604\" data-id=\"12604\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/a209-dress-s-xxl\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12604\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12604\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12604\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12604\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12604\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;A209# Dress S----XXL&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;A209# Dress S----XXL&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"A209# Dress S----XXL\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12604\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/a209-dress-s-xxl\/\">A209# Dress S&#8212;-XXL<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/women\/\" rel=\"tag\">Women<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12517 status-publish last instock product_cat-accessories has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"12517\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb81\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12517\" data-id=\"12517\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb81\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12517\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12517\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12517\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12517\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12517\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;AZ10 trousers XS-3XL (BB81)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;AZ10 trousers XS-3XL (BB81)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"AZ10 trousers XS-3XL (BB81)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12517\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb81\/\">AZ10 trousers XS-3XL (BB81)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/accessories\/\" rel=\"tag\">Accessories<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12519 status-publish first instock product_cat-accessories has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"12519\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb82\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12519\" data-id=\"12519\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb82\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12519\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12519\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12519\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12519\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12519\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;AZ10 trousers XS-3XL (BB82)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;AZ10 trousers XS-3XL (BB82)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"AZ10 trousers XS-3XL (BB82)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12519\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb82\/\">AZ10 trousers XS-3XL (BB82)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/accessories\/\" rel=\"tag\">Accessories<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8baae19 elementor-widget elementor-widget-wd_products_tabs\" data-id=\"8baae19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products_tabs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-tabs wd-products-tabs tabs-design-simple\">\n\t\t\t<div class=\"wd-tabs-header text-center\">\n\t\t\t\t\t\t\t\t\t<div class=\"tabs-name title\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"tabs-text\" data-elementor-setting-key=\"title\">\n\t\t\t\t\t\t\tNew Products\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-nav-wrapper wd-nav-tabs-wrapper tabs-navigation-wrapper\">\n\n\t\t\t\t\t<ul class=\"wd-nav wd-nav-tabs products-tabs-title wd-style-default wd-icon-pos-left\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<li data-atts=\"{&quot;layout&quot;:&quot;grid&quot;,&quot;pagination&quot;:&quot;&quot;,&quot;pagination_arrows_position&quot;:&quot;together&quot;,&quot;items_per_page&quot;:12,&quot;spacing&quot;:&quot;20&quot;,&quot;spacing_tablet&quot;:&quot;&quot;,&quot;spacing_mobile&quot;:&quot;&quot;,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;product_hover&quot;:&quot;inherit&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product_tablet&quot;:0,&quot;stretch_product_mobile&quot;:0,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;highlighted_products&quot;:0,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_bordered_grid_style&quot;:null,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;products_color_scheme&quot;:&quot;default&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;elementor&quot;:true,&quot;sync_parent_id&quot;:null,&quot;lazy_loading&quot;:&quot;&quot;,&quot;slides_per_view&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;wrap&quot;:null,&quot;autoheight&quot;:null,&quot;autoplay&quot;:null,&quot;speed&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;carousel_sync&quot;:null,&quot;sync_child_id&quot;:null,&quot;img_size_custom&quot;:null,&quot;stretch_product&quot;:null,&quot;grid_gallery&quot;:&quot;&quot;,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;post_type&quot;:&quot;bestselling&quot;,&quot;ajax_recently_viewed&quot;:null,&quot;include&quot;:null,&quot;taxonomies&quot;:&quot;&quot;,&quot;orderby&quot;:&quot;&quot;,&quot;offset&quot;:&quot;&quot;,&quot;query_type&quot;:&quot;OR&quot;,&quot;order&quot;:&quot;&quot;,&quot;hide_out_of_stock&quot;:&quot;no&quot;,&quot;meta_key&quot;:null,&quot;exclude&quot;:&quot;&quot;}\" class=\"wd-active\">\n\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-nav-link\">\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<span class=\"tab-label nav-link-text\">\n\t\t\t\t\t\t\t\t\t\tNew product 2\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-tabs-content-wrapper\">\n\t\t\t\t\t<div class=\"wd-sticky-loader\"><span class=\"wd-loader\"><\/span><\/div>\n\t\t\t\t\n\t\t\t\t\t\t\t<div class=\"wd-products-element wd-tab-content wd-active wd-in\">\n\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"products wd-products grid-columns-6 elements-grid wd-grid-g\" data-paged=\"1\" data-atts=\"{&quot;speed&quot;:null,&quot;slides_per_view&quot;:null,&quot;wrap&quot;:null,&quot;autoplay&quot;:null,&quot;autoheight&quot;:null,&quot;hide_pagination_control&quot;:null,&quot;dynamic_pagination_control&quot;:null,&quot;hide_prev_next_buttons&quot;:null,&quot;carousel_arrows_position&quot;:null,&quot;hide_scrollbar&quot;:null,&quot;scroll_per_page&quot;:null,&quot;center_mode&quot;:null,&quot;post_type&quot;:&quot;bestselling&quot;,&quot;carousel_sync&quot;:null,&quot;sync_parent_id&quot;:null,&quot;sync_child_id&quot;:null,&quot;scroll_carousel_init&quot;:null,&quot;disable_overflow_carousel&quot;:null,&quot;include&quot;:null,&quot;meta_key&quot;:null,&quot;ajax_recently_viewed&quot;:null,&quot;pagination_arrows_position&quot;:&quot;together&quot;,&quot;columns&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:6,&quot;sizes&quot;:[]},&quot;products_masonry&quot;:&quot;&quot;,&quot;products_different_sizes&quot;:&quot;&quot;,&quot;product_quantity&quot;:&quot;&quot;,&quot;sale_countdown&quot;:&quot;0&quot;,&quot;stretch_product&quot;:null,&quot;stock_progress_bar&quot;:&quot;0&quot;,&quot;products_divider&quot;:null,&quot;products_bordered_grid&quot;:&quot;0&quot;,&quot;products_bordered_grid_style&quot;:null,&quot;products_with_background&quot;:&quot;0&quot;,&quot;products_shadow&quot;:&quot;0&quot;,&quot;img_size&quot;:&quot;large&quot;,&quot;img_size_custom&quot;:null,&quot;grid_gallery_control&quot;:null,&quot;grid_gallery_enable_arrows&quot;:null,&quot;force_not_ajax&quot;:&quot;no&quot;,&quot;lazy_loading&quot;:&quot;&quot;,&quot;wrapper_classes&quot;:&quot; wd-tab-content wd-active wd-in&quot;,&quot;elementor&quot;:true}\" data-source=\"shortcode\" data-columns=\"6\" data-grid-gallery=\"\" style=\"--wd-col-lg:6;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12591 status-publish instock product_cat-jacket has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"12591\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa7\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12591\" data-id=\"12591\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa7\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12591\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12591\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12591\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12591\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12591\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;YJ25008 jacket (4AA7)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;YJ25008 jacket (4AA7)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"YJ25008 jacket (4AA7)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12591\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa7\/\">YJ25008 jacket (4AA7)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/jacket\/\" rel=\"tag\">jacket<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12553 status-publish instock product_cat-goalkeeper has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"2\" data-id=\"12553\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/12553\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-768x1151.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-1025x1536.jpg 1025w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947.jpg 1080w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12553\" data-id=\"12553\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/12553\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12553\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12553\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12553\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12553\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12553\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;N08 shorts (B427)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;N08 shorts (B427)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"N08 shorts (B427)\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12553\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/12553\/\">N08 shorts (B427)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/goalkeeper\/\" rel=\"tag\">goalkeeper<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12638 status-publish last instock product_cat-new-models has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"3\" data-id=\"12638\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b1d\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12638\" data-id=\"12638\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b1d\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12638\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12638\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12638\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12638\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12638\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1805 Style, Nylon Cool (4B1D)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1805 Style, Nylon Cool (4B1D)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1805 Style, Nylon Cool (4B1D)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12638\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b1d\/\">1805 Style, Nylon Cool (4B1D)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/new-models\/\" rel=\"tag\">New models<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12452 status-publish first instock product_cat-accessories has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"4\" data-id=\"12452\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb8a\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12452\" data-id=\"12452\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb8a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12452\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12452\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12452\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12452\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12452\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;AZ10 trousers XS-3XL (BB8A)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;AZ10 trousers XS-3XL (BB8A)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"AZ10 trousers XS-3XL (BB8A)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12452\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb8a\/\">AZ10 trousers XS-3XL (BB8A)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/accessories\/\" rel=\"tag\">Accessories<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12581 status-publish instock product_cat-jacket has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"12581\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa5\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12581\" data-id=\"12581\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa5\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12581\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12581\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12581\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12581\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12581\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;YJ25008 jacket (4AA5)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;YJ25008 jacket (4AA5)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"YJ25008 jacket (4AA5)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12581\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa5\/\">YJ25008 jacket (4AA5)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/jacket\/\" rel=\"tag\">jacket<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12643 status-publish instock product_cat-new-models has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"6\" data-id=\"12643\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b2d\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12643\" data-id=\"12643\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b2d\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12643\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12643\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12643\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12643\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12643\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1805 Style, Nylon Cool (4B2D)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1805 Style, Nylon Cool (4B2D)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1805 Style, Nylon Cool (4B2D)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12643\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b2d\/\">1805 Style, Nylon Cool (4B2D)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/new-models\/\" rel=\"tag\">New models<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12517 status-publish last instock product_cat-accessories has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"12517\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb81\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12517\" data-id=\"12517\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb81\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12517\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12517\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12517\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12517\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12517\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;AZ10 trousers XS-3XL (BB81)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;AZ10 trousers XS-3XL (BB81)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"AZ10 trousers XS-3XL (BB81)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12517\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb81\/\">AZ10 trousers XS-3XL (BB81)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/accessories\/\" rel=\"tag\">Accessories<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12586 status-publish first instock product_cat-jacket has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"12586\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa6\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12586\" data-id=\"12586\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa6\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12586\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12586\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12586\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12586\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12586\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;YJ25008 jacket (4AA6)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;YJ25008 jacket (4AA6)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"YJ25008 jacket (4AA6)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12586\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa6\/\">YJ25008 jacket (4AA6)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/jacket\/\" rel=\"tag\">jacket<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12648 status-publish instock product_cat-package-includes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"12648\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f26\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12648\" data-id=\"12648\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f26\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12648\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12648\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12648\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12648\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12648\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B306 Hooded Four Seasons Jacket (0F26)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B306 Hooded Four Seasons Jacket (0F26)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B306 Hooded Four Seasons Jacket (0F26)\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12648\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f26\/\">B306 Hooded Four Seasons Jacket (0F26)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/package-includes\/\" rel=\"tag\">Package includes<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12519 status-publish instock product_cat-accessories has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"12519\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb82\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12519\" data-id=\"12519\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb82\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12519\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12519\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12519\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12519\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12519\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;AZ10 trousers XS-3XL (BB82)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;AZ10 trousers XS-3XL (BB82)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"AZ10 trousers XS-3XL (BB82)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12519\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb82\/\">AZ10 trousers XS-3XL (BB82)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/accessories\/\" rel=\"tag\">Accessories<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12653 status-publish last instock product_cat-package-includes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"12653\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f28\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12653\" data-id=\"12653\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f28\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12653\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12653\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12653\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12653\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12653\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B306 Hooded Four Seasons Jacket (0F28)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B306 Hooded Four Seasons Jacket (0F28)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B306 Hooded Four Seasons Jacket (0F28)\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12653\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f28\/\">B306 Hooded Four Seasons Jacket (0F28)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/package-includes\/\" rel=\"tag\">Package includes<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick wd-col product-grid-item product type-product post-12521 status-publish first instock product_cat-fitness-clothes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"12521\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f92a\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12521\" data-id=\"12521\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f92a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12521\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12521\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12521\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12521\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12521\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B251 Half-length long sleeves (F92A)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B251 Half-length long sleeves (F92A)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B251 Half-length long sleeves (F92A)\" data-price=\"45\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12521\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f92a\/\">B251 Half-length long sleeves (F92A)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/fitness-clothes\/\" rel=\"tag\">Fitness Clothes<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>45.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\n\t\t\t\t<\/div>\n\t\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-3549d93 e-flex e-con-boxed e-con e-parent\" data-id=\"3549d93\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-29475b5 elementor-widget elementor-widget-wd_countdown_timer\" data-id=\"29475b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_countdown_timer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-countdown-timer color-scheme- text-center\">\n\t\t\t<div class=\"wd-timer wd-size-medium wd-style-standard\" data-end-date=\"2026-07-13\" data-timezone=\"GMT\" data-hide-on-finish=\"no\">\n\t\t\t\t<span class=\"wd-timer-days\">\n\t\t\t\t\t<span class=\"wd-timer-value\">\n\t\t\t\t\t\t0\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-timer-text\">\n\t\t\t\t\t\tdias\t\t\t\t\t<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-timer-hours\">\n\t\t\t\t\t<span class=\"wd-timer-value\">\n\t\t\t\t\t\t00\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-timer-text\">\n\t\t\t\t\t\thora\t\t\t\t\t<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-timer-min\">\n\t\t\t\t\t<span class=\"wd-timer-value\">\n\t\t\t\t\t\t00\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-timer-text\">\n\t\t\t\t\t\tmin\t\t\t\t\t<\/span>\n\t\t\t\t<\/span>\n\t\t\t\t<span class=\"wd-timer-sec\">\n\t\t\t\t\t<span class=\"wd-timer-value\">\n\t\t\t\t\t\t00\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<span class=\"wd-timer-text\">\n\t\t\t\t\t\tsc\t\t\t\t\t<\/span>\n\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-23df2be wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"23df2be\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div id=\"carousel-843\" class=\"wd-carousel-container  wd-products-element wd-products products wd-carousel-dis-mb wd-off-md wd-off-sm\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\"wd-carousel wd-grid\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:5;--wd-col-md:4;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12591 status-publish instock product_cat-jacket has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"1\" data-id=\"12591\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa7\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595754FEF.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12591\" data-id=\"12591\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa7\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12591\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12591\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12591\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12591\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12591\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;YJ25008 jacket (4AA7)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;YJ25008 jacket (4AA7)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"YJ25008 jacket (4AA7)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12591\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa7\/\">YJ25008 jacket (4AA7)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/jacket\/\" rel=\"tag\">jacket<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12586 status-publish instock product_cat-jacket has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"2\" data-id=\"12586\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa6\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u59571F3A7.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12586\" data-id=\"12586\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa6\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12586\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12586\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12586\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12586\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12586\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;YJ25008 jacket (4AA6)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;YJ25008 jacket (4AA6)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"YJ25008 jacket (4AA6)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12586\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa6\/\">YJ25008 jacket (4AA6)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/jacket\/\" rel=\"tag\">jacket<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12581 status-publish last instock product_cat-jacket has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"3\" data-id=\"12581\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa5\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/YJ24008\u5916\u595761079.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12581\" data-id=\"12581\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa5\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12581\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12581\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12581\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12581\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12581\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;YJ25008 jacket (4AA5)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;YJ25008 jacket (4AA5)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"YJ25008 jacket (4AA5)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12581\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/yj25008-jacket-4aa5\/\">YJ25008 jacket (4AA5)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/jacket\/\" rel=\"tag\">jacket<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12546 status-publish first instock product_cat-goalkeeper has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"4\" data-id=\"12546\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/n08-shorts-b429\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e47F86C-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e47F86C-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e47F86C-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e47F86C-768x1151.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e47F86C-1025x1536.jpg 1025w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e47F86C-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e47F86C-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e47F86C.jpg 1080w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12546\" data-id=\"12546\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/n08-shorts-b429\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12546\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12546\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12546\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12546\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12546\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;N08 shorts (B429)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;N08 shorts (B429)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"N08 shorts (B429)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12546\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/n08-shorts-b429\/\">N08 shorts (B429)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/goalkeeper\/\" rel=\"tag\">goalkeeper<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12548 status-publish instock product_cat-goalkeeper has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"5\" data-id=\"12548\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/n08-shorts-b428\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e4D5942-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e4D5942-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e4D5942-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e4D5942-768x1151.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e4D5942-1025x1536.jpg 1025w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e4D5942-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e4D5942-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e4D5942.jpg 1080w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12548\" data-id=\"12548\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/n08-shorts-b428\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12548\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12548\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12548\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12548\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12548\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;N08 shorts (B428)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;N08 shorts (B428)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"N08 shorts (B428)\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12548\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/n08-shorts-b428\/\">N08 shorts (B428)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/goalkeeper\/\" rel=\"tag\">goalkeeper<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12553 status-publish instock product_cat-goalkeeper has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"6\" data-id=\"12553\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/12553\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-768x1151.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-1025x1536.jpg 1025w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/N02\u77ed\u88e439947.jpg 1080w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12553\" data-id=\"12553\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/12553\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12553\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12553\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12553\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12553\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12553\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;N08 shorts (B427)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;N08 shorts (B427)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"N08 shorts (B427)\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12553\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/12553\/\">N08 shorts (B427)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/goalkeeper\/\" rel=\"tag\">goalkeeper<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12658 status-publish last instock product_cat-package-includes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"7\" data-id=\"12658\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f29\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12658\" data-id=\"12658\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f29\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12658\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12658\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12658\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12658\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12658\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B306 Hooded Four Seasons Jacket (0F29)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B306 Hooded Four Seasons Jacket (0F29)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B306 Hooded Four Seasons Jacket (0F29)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12658\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f29\/\">B306 Hooded Four Seasons Jacket (0F29)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/package-includes\/\" rel=\"tag\">Package includes<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12653 status-publish first instock product_cat-package-includes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"8\" data-id=\"12653\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f28\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040626D0439.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12653\" data-id=\"12653\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f28\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12653\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12653\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12653\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12653\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12653\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B306 Hooded Four Seasons Jacket (0F28)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B306 Hooded Four Seasons Jacket (0F28)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B306 Hooded Four Seasons Jacket (0F28)\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12653\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f28\/\">B306 Hooded Four Seasons Jacket (0F28)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/package-includes\/\" rel=\"tag\">Package includes<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12648 status-publish instock product_cat-package-includes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"9\" data-id=\"12648\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f26\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04062414492.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12648\" data-id=\"12648\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f26\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12648\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12648\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12648\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12648\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12648\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B306 Hooded Four Seasons Jacket (0F26)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B306 Hooded Four Seasons Jacket (0F26)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B306 Hooded Four Seasons Jacket (0F26)\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12648\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b306-hooded-four-seasons-jacket-0f26\/\">B306 Hooded Four Seasons Jacket (0F26)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/package-includes\/\" rel=\"tag\">Package includes<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12541 status-publish instock product_cat-fitness-clothes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"10\" data-id=\"12541\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f96a\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe3171B-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe3171B-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe3171B-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe3171B-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe3171B-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe3171B-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe3171B-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe3171B-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe3171B-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe3171B-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe3171B.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12541\" data-id=\"12541\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f96a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12541\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12541\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12541\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12541\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12541\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B251 Half-length long sleeves (F96A)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B251 Half-length long sleeves (F96A)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B251 Half-length long sleeves (F96A)\" data-price=\"30\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12541\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f96a\/\">B251 Half-length long sleeves (F96A)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/fitness-clothes\/\" rel=\"tag\">Fitness Clothes<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>30.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12536 status-publish last instock product_cat-fitness-clothes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"11\" data-id=\"12536\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f95a\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe28D6D-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe28D6D-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe28D6D-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe28D6D-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe28D6D-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe28D6D-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe28D6D-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe28D6D-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe28D6D-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe28D6D-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe28D6D.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12536\" data-id=\"12536\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f95a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12536\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12536\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12536\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12536\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12536\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B251 Half-length long sleeves (F95A)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B251 Half-length long sleeves (F95A)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B251 Half-length long sleeves (F95A)\" data-price=\"25\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12536\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f95a\/\">B251 Half-length long sleeves (F95A)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/fitness-clothes\/\" rel=\"tag\">Fitness Clothes<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>25.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12531 status-publish first instock product_cat-fitness-clothes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"12\" data-id=\"12531\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f94a\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe15792-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe15792-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe15792-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe15792-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe15792-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe15792-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe15792-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe15792-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe15792-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe15792-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56fe15792.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12531\" data-id=\"12531\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f94a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12531\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12531\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12531\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12531\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12531\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B251 Half-length long sleeves (F94A)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B251 Half-length long sleeves (F94A)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B251 Half-length long sleeves (F94A)\" data-price=\"35\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12531\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f94a\/\">B251 Half-length long sleeves (F94A)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/fitness-clothes\/\" rel=\"tag\">Fitness Clothes<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>35.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12526 status-publish instock product_cat-fitness-clothes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"13\" data-id=\"12526\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f93a\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feAE23A-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feAE23A-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feAE23A-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feAE23A-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feAE23A-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feAE23A-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feAE23A-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feAE23A-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feAE23A-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feAE23A-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feAE23A.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12526\" data-id=\"12526\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f93a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12526\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12526\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12526\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12526\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12526\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B251 Half-length long sleeves (F93A)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B251 Half-length long sleeves (F93A)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B251 Half-length long sleeves (F93A)\" data-price=\"40\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12526\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f93a\/\">B251 Half-length long sleeves (F93A)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/fitness-clothes\/\" rel=\"tag\">Fitness Clothes<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>40.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12521 status-publish instock product_cat-fitness-clothes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"14\" data-id=\"12521\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f92a\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/B661\u957f\u88963D\u56feDE8C3.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12521\" data-id=\"12521\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f92a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12521\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12521\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12521\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12521\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12521\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B251 Half-length long sleeves (F92A)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B251 Half-length long sleeves (F92A)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B251 Half-length long sleeves (F92A)\" data-price=\"45\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12521\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b251-half-length-long-sleeves-f92a\/\">B251 Half-length long sleeves (F92A)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/fitness-clothes\/\" rel=\"tag\">Fitness Clothes<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>45.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12674 status-publish last instock product_cat-package-includes has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"15\" data-id=\"12674\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b152-round-neck-long-sleeves-94c0\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04050373CD7-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04050373CD7-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04050373CD7-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04050373CD7-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04050373CD7-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04050373CD7-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04050373CD7-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04050373CD7-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04050373CD7-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04050373CD7-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-04050373CD7.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12674\" data-id=\"12674\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b152-round-neck-long-sleeves-94c0\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12674\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12674\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12674\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12674\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12674\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B152 round neck long sleeves (94C0)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B152 round neck long sleeves (94C0)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B152 round neck long sleeves (94C0)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12674\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b152-round-neck-long-sleeves-94c0\/\">B152 round neck long sleeves (94C0)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/package-includes\/\" rel=\"tag\">Package includes<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12669 status-publish first instock product_cat-short-sleeve-suit has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"16\" data-id=\"12669\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/b152-round-neck-long-sleeves-93c0\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040488B12AD-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040488B12AD-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040488B12AD-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040488B12AD-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040488B12AD-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040488B12AD-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040488B12AD-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040488B12AD-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040488B12AD-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040488B12AD-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-040488B12AD.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12669\" data-id=\"12669\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/b152-round-neck-long-sleeves-93c0\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12669\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12669\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12669\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12669\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12669\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;B152 round neck long sleeves (93C0)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;B152 round neck long sleeves (93C0)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"B152 round neck long sleeves (93C0)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12669\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/b152-round-neck-long-sleeves-93c0\/\">B152 round neck long sleeves (93C0)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/short-sleeve-suit\/\" rel=\"tag\">Short sleeve suit<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12452 status-publish instock product_cat-accessories has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"17\" data-id=\"12452\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb8a\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feC31E1.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12452\" data-id=\"12452\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb8a\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12452\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12452\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12452\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12452\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12452\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;AZ10 trousers XS-3XL (BB8A)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;AZ10 trousers XS-3XL (BB8A)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"AZ10 trousers XS-3XL (BB8A)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12452\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb8a\/\">AZ10 trousers XS-3XL (BB8A)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/accessories\/\" rel=\"tag\">Accessories<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12519 status-publish instock product_cat-accessories has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"18\" data-id=\"12519\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb82\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56fe836A2.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12519\" data-id=\"12519\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb82\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12519\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12519\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12519\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12519\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12519\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;AZ10 trousers XS-3XL (BB82)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;AZ10 trousers XS-3XL (BB82)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"AZ10 trousers XS-3XL (BB82)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12519\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb82\/\">AZ10 trousers XS-3XL (BB82)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/accessories\/\" rel=\"tag\">Accessories<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12517 status-publish last instock product_cat-accessories has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"19\" data-id=\"12517\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb81\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-1024x1024.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-300x300.jpg 300w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-150x150.jpg 150w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-768x768.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-1536x1536.jpg 1536w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-12x12.jpg 12w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-600x600.jpg 600w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-1200x1200.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED-148x148.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/AZ02\u957f\u88e43D\u56feE1FED.jpg 1600w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12517\" data-id=\"12517\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb81\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12517\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12517\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12517\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12517\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12517\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;AZ10 trousers XS-3XL (BB81)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;AZ10 trousers XS-3XL (BB81)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"AZ10 trousers XS-3XL (BB81)\" data-price=\"15\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12517\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/az10-trousers-xs-3xl-bb81\/\">AZ10 trousers XS-3XL (BB81)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/accessories\/\" rel=\"tag\">Accessories<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>15.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12604 status-publish first instock product_cat-women has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"20\" data-id=\"12604\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/a209-dress-s-xxl\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-819x1024.jpg 819w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-240x300.jpg 240w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-768x960.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-1229x1536.jpg 1229w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-10x12.jpg 10w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-1200x1500.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6-148x185.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272FE8E6.jpg 1600w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12604\" data-id=\"12604\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/a209-dress-s-xxl\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12604\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12604\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12604\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12604\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12604\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;A209# Dress S----XXL&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;A209# Dress S----XXL&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"A209# Dress S----XXL\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12604\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/a209-dress-s-xxl\/\">A209# Dress S&#8212;-XXL<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/women\/\" rel=\"tag\">Women<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12596 status-publish instock product_cat-women has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"21\" data-id=\"12596\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/a208-dress-s-xxl\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-819x1024.jpg 819w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-240x300.jpg 240w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-768x960.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-1229x1536.jpg 1229w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-10x12.jpg 10w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-1200x1500.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8-148x185.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/\u8ff7\u5f69\u7c89\u8272B57F8.jpg 1600w\" sizes=\"(max-width: 819px) 100vw, 819px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12596\" data-id=\"12596\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/a208-dress-s-xxl\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12596\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12596\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12596\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12596\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12596\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;A208# Dress S----XXL&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;A208# Dress S----XXL&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"A208# Dress S----XXL\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12596\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/a208-dress-s-xxl\/\">A208# Dress S&#8212;-XXL<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/women\/\" rel=\"tag\">Women<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12663 status-publish instock product_cat-short-sleeve-suit has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"22\" data-id=\"12663\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/a081-hooded-four-seasons-fitness-pants\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"853\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-853x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-853x1024.jpg 853w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-250x300.jpg 250w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-768x922.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-1280x1536.jpg 1280w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-10x12.jpg 10w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-1200x1440.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58-148x178.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/02694DBC58.jpg 1600w\" sizes=\"(max-width: 853px) 100vw, 853px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12663\" data-id=\"12663\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/a081-hooded-four-seasons-fitness-pants\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12663\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12663\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12663\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12663\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12663\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;A081 hooded four seasons fitness pants&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;A081 hooded four seasons fitness pants&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"A081 hooded four seasons fitness pants\" data-price=\"20\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12663\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/a081-hooded-four-seasons-fitness-pants\/\">A081 hooded four seasons fitness pants<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/short-sleeve-suit\/\" rel=\"tag\">Short sleeve suit<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>20.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12643 status-publish last instock product_cat-new-models has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"23\" data-id=\"12643\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b2d\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00830-\u526f\u672c99AB0.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12643\" data-id=\"12643\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b2d\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12643\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12643\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12643\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12643\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12643\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1805 Style, Nylon Cool (4B2D)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1805 Style, Nylon Cool (4B2D)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1805 Style, Nylon Cool (4B2D)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12643\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b2d\/\">1805 Style, Nylon Cool (4B2D)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/new-models\/\" rel=\"tag\">New models<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12638 status-publish first instock product_cat-new-models has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"24\" data-id=\"12638\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b1d\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00768-\u526f\u672c2C252.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12638\" data-id=\"12638\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b1d\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12638\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12638\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12638\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12638\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12638\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1805 Style, Nylon Cool (4B1D)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1805 Style, Nylon Cool (4B1D)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1805 Style, Nylon Cool (4B1D)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12638\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b1d\/\">1805 Style, Nylon Cool (4B1D)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/new-models\/\" rel=\"tag\">New models<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12633 status-publish instock product_cat-new-models has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"25\" data-id=\"12633\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b0d\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00765-\u526f\u672c61059.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12633\" data-id=\"12633\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b0d\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12633\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12633\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12633\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12633\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12633\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1805 Style, Nylon Cool (4B0D)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1805 Style, Nylon Cool (4B0D)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1805 Style, Nylon Cool (4B0D)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12633\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1805-style-nylon-cool-4b0d\/\">1805 Style, Nylon Cool (4B0D)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/new-models\/\" rel=\"tag\">New models<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12628 status-publish instock product_cat-mens has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"26\" data-id=\"12628\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1802-style-nylon-cool-pique-b389\/\" class=\"product-image-link\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00728-\u526f\u672cBAD2D.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12628\" data-id=\"12628\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1802-style-nylon-cool-pique-b389\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12628\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12628\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12628\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12628\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12628\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1802 style, nylon cool pique (B389)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1802 style, nylon cool pique (B389)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1802 style, nylon cool pique (B389)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12628\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1802-style-nylon-cool-pique-b389\/\">1802 style, nylon cool pique (B389)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/mens\/\" rel=\"tag\">Men\u2019s<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12623 status-publish last instock product_cat-mens has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"27\" data-id=\"12623\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1802-style-nylon-cool-pique-b388\/\" class=\"product-image-link\">\n\t\t\t<img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00725-\u526f\u672c1CA19.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12623\" data-id=\"12623\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1802-style-nylon-cool-pique-b388\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12623\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12623\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12623\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12623\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12623\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1802 style, nylon cool pique (B388)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1802 style, nylon cool pique (B388)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1802 style, nylon cool pique (B388)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12623\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1802-style-nylon-cool-pique-b388\/\">1802 style, nylon cool pique (B388)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/mens\/\" rel=\"tag\">Men\u2019s<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12618 status-publish first instock product_cat-mens has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"28\" data-id=\"12618\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1801-style-nylon-cool-pique-b386\/\" class=\"product-image-link\">\n\t\t\t<img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00721-\u526f\u672c2CD9C.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12618\" data-id=\"12618\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1801-style-nylon-cool-pique-b386\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12618\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12618\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12618\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12618\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12618\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1801 style, nylon cool pique (B386)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1801 style, nylon cool pique (B386)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1801 style, nylon cool pique (B386)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12618\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1801-style-nylon-cool-pique-b386\/\">1801 style, nylon cool pique (B386)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/mens\/\" rel=\"tag\">Men\u2019s<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-hover-quick product-grid-item product type-product post-12613 status-publish instock product_cat-mens has-post-thumbnail shipping-taxable purchasable product-type-simple\" data-loop=\"29\" data-id=\"12613\">\n\t\t\t\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/chstar.xyz\/pt\/produto\/1801-style-nylon-cool-pique-b385\/\" class=\"product-image-link\">\n\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-683x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-683x1024.jpg 683w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-200x300.jpg 200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-768x1152.jpg 768w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-1024x1536.jpg 1024w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-1365x2048.jpg 1365w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-8x12.jpg 8w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-1200x1800.jpg 1200w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264-148x222.jpg 148w, https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/00716-\u526f\u672c6B264.jpg 1600w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/>\t\t<\/a>\n\n\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/compare\/?product_id=12613\" data-id=\"12613\" rel=\"nofollow\" data-added-text=\"Comparar Produtos\">\n\t\t\t\t<span>Comparar<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/chstar.xyz\/pt\/produto\/1801-style-nylon-cool-pique-b385\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"12613\"\n\t\t\t\t>Vista R\u00e1pida<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/chstar.xyz\/pt\/wishlist\/\" data-key=\"caaf014870\" data-product-id=\"12613\" rel=\"nofollow\" data-added-text=\"Navegar na lista de desejos\">\n\t\t\t\t\t<span>Adicionar aos favoritos<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"\/pt\/wp-json\/wp\/v2\/pages\/25?add-to-cart=12613\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_12613\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart add-to-cart-loop\" data-product_id=\"12613\" data-product_sku=\"\" aria-label=\"Adiciona ao carrinho: &ldquo;1801 style, nylon cool pique (B385)&rdquo;\" rel=\"nofollow\" data-success_message=\"&ldquo;1801 style, nylon cool pique (B385)&rdquo; foi adicionado ao seu carrinho\" data-product_name=\"1801 style, nylon cool pique (B385)\" data-price=\"18\" role=\"button\"><span>Adicionar<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_12613\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/chstar.xyz\/pt\/produto\/1801-style-nylon-cool-pique-b385\/\">1801 style, nylon cool pique (B385)<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/chstar.xyz\/pt\/categoria-produto\/mens\/\" rel=\"tag\">Men\u2019s<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&euro;<\/span>18.00<\/bdi><\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>New Products New product 1 Array New Products New product 2 Array 0 days 00 hr 00 min 00 sc<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-25","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jersey . NBA. Sportswear .fotball .Sporting Goods<\/title>\n<meta name=\"description\" content=\"Arsenal\uff0cChelsea\uff0cEverton\uff0cLeicester City\uff0cLiverpool\uff0cManchester City\uff0cManchester United\uff0cNewcastle United\uff0cTottenham Hotspur\uff0cWest Ham United\uff0cBarcelona\uff0cReal Sociedad\uff0cReal Betis\uff0cSevilla\uff0cAtletico Madrid\uff0cAthletic Club\uff0cReal Madrid\uff0cValencia\uff0cMilan\uff0cInternazionale\uff0cJuventus\uff0cLazio\uff0cNapoli\uff0cRoma\uff0cBorussia Dortmund\uff0cEintracht Frankfurt\uff0cBayer Leverkusen\uff0cBayern Munich\uff0cOlympique Marseille\uff0cPSG\uff0cOlympique Lyonnais\uff0cAl Nassr\uff0cAl-Hilal Saudi\uff0cInter Miami\uff0cBenfica\uff0cPorto\uff0cSporting CP\uff0cCeltic FC\uff0c\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/chstar.xyz\/pt\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jersey . NBA. Sportswear .fotball .Sporting Goods\" \/>\n<meta property=\"og:description\" content=\"Arsenal\uff0cChelsea\uff0cEverton\uff0cLeicester City\uff0cLiverpool\uff0cManchester City\uff0cManchester United\uff0cNewcastle United\uff0cTottenham Hotspur\uff0cWest Ham United\uff0cBarcelona\uff0cReal Sociedad\uff0cReal Betis\uff0cSevilla\uff0cAtletico Madrid\uff0cAthletic Club\uff0cReal Madrid\uff0cValencia\uff0cMilan\uff0cInternazionale\uff0cJuventus\uff0cLazio\uff0cNapoli\uff0cRoma\uff0cBorussia Dortmund\uff0cEintracht Frankfurt\uff0cBayer Leverkusen\uff0cBayern Munich\uff0cOlympique Marseille\uff0cPSG\uff0cOlympique Lyonnais\uff0cAl Nassr\uff0cAl-Hilal Saudi\uff0cInter Miami\uff0cBenfica\uff0cPorto\uff0cSporting CP\uff0cCeltic FC\uff0c\" \/>\n<meta property=\"og:url\" content=\"https:\/\/chstar.xyz\/pt\/\" \/>\n<meta property=\"og:site_name\" content=\"Xiao\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-20T05:13:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-1024x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/chstar.xyz\/\",\"url\":\"https:\/\/chstar.xyz\/\",\"name\":\"Jersey . NBA. Sportswear .fotball .Sporting Goods\",\"isPartOf\":{\"@id\":\"https:\/\/chstar.xyz\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/chstar.xyz\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/chstar.xyz\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-1024x1024.jpg\",\"datePublished\":\"2022-09-07T13:52:36+00:00\",\"dateModified\":\"2025-10-20T05:13:11+00:00\",\"description\":\"Arsenal\uff0cChelsea\uff0cEverton\uff0cLeicester City\uff0cLiverpool\uff0cManchester City\uff0cManchester United\uff0cNewcastle United\uff0cTottenham Hotspur\uff0cWest Ham United\uff0cBarcelona\uff0cReal Sociedad\uff0cReal Betis\uff0cSevilla\uff0cAtletico Madrid\uff0cAthletic Club\uff0cReal Madrid\uff0cValencia\uff0cMilan\uff0cInternazionale\uff0cJuventus\uff0cLazio\uff0cNapoli\uff0cRoma\uff0cBorussia Dortmund\uff0cEintracht Frankfurt\uff0cBayer Leverkusen\uff0cBayern Munich\uff0cOlympique Marseille\uff0cPSG\uff0cOlympique Lyonnais\uff0cAl Nassr\uff0cAl-Hilal Saudi\uff0cInter Miami\uff0cBenfica\uff0cPorto\uff0cSporting CP\uff0cCeltic FC\uff0c\",\"breadcrumb\":{\"@id\":\"https:\/\/chstar.xyz\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/chstar.xyz\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/chstar.xyz\/#primaryimage\",\"url\":\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-1024x1024.jpg\",\"contentUrl\":\"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-1024x1024.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/chstar.xyz\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u9996\u9875\",\"item\":\"https:\/\/chstar.xyz\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Home\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/chstar.xyz\/fr\/#website\",\"url\":\"https:\/\/chstar.xyz\/fr\/\",\"name\":\"Xiao\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/chstar.xyz\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jersey . NBA. Sportswear .fotball .Sporting Goods","description":"Arsenal\uff0cChelsea\uff0cEverton\uff0cLeicester City\uff0cLiverpool\uff0cManchester City\uff0cManchester United\uff0cNewcastle United\uff0cTottenham Hotspur\uff0cWest Ham United\uff0cBarcelona\uff0cReal Sociedad\uff0cReal Betis\uff0cSevilla\uff0cAtletico Madrid\uff0cAthletic Club\uff0cReal Madrid\uff0cValencia\uff0cMilan\uff0cInternazionale\uff0cJuventus\uff0cLazio\uff0cNapoli\uff0cRoma\uff0cBorussia Dortmund\uff0cEintracht Frankfurt\uff0cBayer Leverkusen\uff0cBayern Munich\uff0cOlympique Marseille\uff0cPSG\uff0cOlympique Lyonnais\uff0cAl Nassr\uff0cAl-Hilal Saudi\uff0cInter Miami\uff0cBenfica\uff0cPorto\uff0cSporting CP\uff0cCeltic FC\uff0c","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/chstar.xyz\/pt\/","og_locale":"pt_PT","og_type":"article","og_title":"Jersey . NBA. Sportswear .fotball .Sporting Goods","og_description":"Arsenal\uff0cChelsea\uff0cEverton\uff0cLeicester City\uff0cLiverpool\uff0cManchester City\uff0cManchester United\uff0cNewcastle United\uff0cTottenham Hotspur\uff0cWest Ham United\uff0cBarcelona\uff0cReal Sociedad\uff0cReal Betis\uff0cSevilla\uff0cAtletico Madrid\uff0cAthletic Club\uff0cReal Madrid\uff0cValencia\uff0cMilan\uff0cInternazionale\uff0cJuventus\uff0cLazio\uff0cNapoli\uff0cRoma\uff0cBorussia Dortmund\uff0cEintracht Frankfurt\uff0cBayer Leverkusen\uff0cBayern Munich\uff0cOlympique Marseille\uff0cPSG\uff0cOlympique Lyonnais\uff0cAl Nassr\uff0cAl-Hilal Saudi\uff0cInter Miami\uff0cBenfica\uff0cPorto\uff0cSporting CP\uff0cCeltic FC\uff0c","og_url":"https:\/\/chstar.xyz\/pt\/","og_site_name":"Xiao","article_modified_time":"2025-10-20T05:13:11+00:00","og_image":[{"url":"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-1024x1024.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Tempo estimado de leitura":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/chstar.xyz\/","url":"https:\/\/chstar.xyz\/","name":"Jersey . NBA. Sportswear .fotball .Sporting Goods","isPartOf":{"@id":"https:\/\/chstar.xyz\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/chstar.xyz\/#primaryimage"},"image":{"@id":"https:\/\/chstar.xyz\/#primaryimage"},"thumbnailUrl":"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-1024x1024.jpg","datePublished":"2022-09-07T13:52:36+00:00","dateModified":"2025-10-20T05:13:11+00:00","description":"Arsenal\uff0cChelsea\uff0cEverton\uff0cLeicester City\uff0cLiverpool\uff0cManchester City\uff0cManchester United\uff0cNewcastle United\uff0cTottenham Hotspur\uff0cWest Ham United\uff0cBarcelona\uff0cReal Sociedad\uff0cReal Betis\uff0cSevilla\uff0cAtletico Madrid\uff0cAthletic Club\uff0cReal Madrid\uff0cValencia\uff0cMilan\uff0cInternazionale\uff0cJuventus\uff0cLazio\uff0cNapoli\uff0cRoma\uff0cBorussia Dortmund\uff0cEintracht Frankfurt\uff0cBayer Leverkusen\uff0cBayern Munich\uff0cOlympique Marseille\uff0cPSG\uff0cOlympique Lyonnais\uff0cAl Nassr\uff0cAl-Hilal Saudi\uff0cInter Miami\uff0cBenfica\uff0cPorto\uff0cSporting CP\uff0cCeltic FC\uff0c","breadcrumb":{"@id":"https:\/\/chstar.xyz\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/chstar.xyz\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/chstar.xyz\/#primaryimage","url":"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-1024x1024.jpg","contentUrl":"https:\/\/chstar.xyz\/wp-content\/uploads\/2025\/06\/IMG-0406293C0E4-1024x1024.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/chstar.xyz\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u9996\u9875","item":"https:\/\/chstar.xyz\/"},{"@type":"ListItem","position":2,"name":"Home"}]},{"@type":"WebSite","@id":"https:\/\/chstar.xyz\/fr\/#website","url":"https:\/\/chstar.xyz\/fr\/","name":"Xiao","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/chstar.xyz\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/chstar.xyz\/pt\/wp-json\/wp\/v2\/pages\/25","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chstar.xyz\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/chstar.xyz\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/chstar.xyz\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/chstar.xyz\/pt\/wp-json\/wp\/v2\/comments?post=25"}],"version-history":[{"count":48,"href":"https:\/\/chstar.xyz\/pt\/wp-json\/wp\/v2\/pages\/25\/revisions"}],"predecessor-version":[{"id":12739,"href":"https:\/\/chstar.xyz\/pt\/wp-json\/wp\/v2\/pages\/25\/revisions\/12739"}],"wp:attachment":[{"href":"https:\/\/chstar.xyz\/pt\/wp-json\/wp\/v2\/media?parent=25"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}